{"id":18794,"date":"2025-07-16T17:13:25","date_gmt":"2025-07-16T15:13:25","guid":{"rendered":"https:\/\/tourisme-en-champagne.com\/hlocha051v500m6z-en"},"modified":"2026-08-29T12:35:09","modified_gmt":"2026-08-29T10:35:09","slug":"gite-du-champagne-patis-paille","status":"publish","type":"hebergement","link":"https:\/\/tourisme-en-champagne.com\/en\/hebergement\/gite-du-champagne-patis-paille\/","title":{"rendered":"G\u00eete du Champagne Patis Paille"},"author":2,"template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"class_list":["post-18794","hebergement","type-hebergement","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tourisme-en-champagne.com\/en\/wp-json\/wp\/v2\/hebergement\/18794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tourisme-en-champagne.com\/en\/wp-json\/wp\/v2\/hebergement"}],"about":[{"href":"https:\/\/tourisme-en-champagne.com\/en\/wp-json\/wp\/v2\/types\/hebergement"}],"author":[{"embeddable":true,"href":"https:\/\/tourisme-en-champagne.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/tourisme-en-champagne.com\/en\/wp-json\/wp\/v2\/media?parent=18794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}